{"id":5545,"date":"2019-05-05T22:18:16","date_gmt":"2019-05-05T20:18:16","guid":{"rendered":"https:\/\/www.nerdiy.de\/?p=5545"},"modified":"2024-04-11T21:59:05","modified_gmt":"2024-04-11T19:59:05","slug":"howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen","status":"publish","type":"post","link":"https:\/\/nerdiy.de\/de_de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/","title":{"rendered":"HowTo: Elektronik &#8211; L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen"},"content":{"rendered":"<p>Wer den Artikel <em><a href=\"https:\/\/www.nerdiy.de\/howto-elektronik-mein-freund-der-loetkolben\/\"><strong>Elektronik &#8211; Mein Freund der L\u00f6tkolben<\/strong><\/a><\/em> bereits gelesen hat, hat vllt. gemerkt, dass man \u00fcber dieses Thema tats\u00e4chlich ziemlich viel schreiben kann. Und dabei geht es nur um das korrekte verbinden zweier Kontaktfl\u00e4chen. Das trennen dieser bereits verbundenen Kontaktfl\u00e4chen ist dagegen nochmal eine ganz andere Sache.<\/p>\n<p>Bei einfachen Bauteilen und verbundenen Leitungen ist die Verbindung schnell getrennt. Bei mehrpoligen SMD-Bauteilen kann es dagegen schon schwieriger werden.<\/p>\n<p>Der folgende Artikel sollte f\u00fcr viele &#8220;Trennungs-Situationen&#8221; zumindest einen Einstieg erm\u00f6glichen.<\/p>\n<hr \/>\n<h2><span style=\"color: #ff0000;\">Sicherheitshinweise <\/span><\/h2>\r\n<p><span style=\"color: #ff0000;\">Ich wei\u00df die folgenden Hinweise sind immer irgendwie l\u00e4stig und wirken unn\u00f6tig. Aber leider haben schon viele Menschen die es \"besser\" wussten aus Leichtsinnigkeit Augen, Finger oder anderes verloren bzw. sich verletzt. Im Vergleich dazu ist ein Datenverlust fast nicht der Rede Wert, aber auch diese k\u00f6nnen echt \u00e4rgerlich sein. Deswegen nehmt Euch bitte f\u00fcnf Minuten Zeit um die Sicherheitshinweise zu lesen. Denn auch das coolste Projekt ist keine Verletzung oder anderen \u00c4rger wert.<\/span><br \/><strong><em><a href=\"https:\/\/www.nerdiy.de\/sicherheitshinweise\/\"><span style=\"color: #ff0000;\">https:\/\/www.nerdiy.de\/sicherheitshinweise\/<\/span><\/a><\/em><\/strong><\/p>\r\n<h2>Affiliatelinks\/Werbelinks<\/h2>\r\n<p><em>Die hier in aufgef\u00fchrten Links zu Online-Shops sind sogenannte Affiliate-Links. Wenn Du auf so einen Affiliate-Link klickst und \u00fcber diesen Link einkaufst, bekommt Nerdiy.de von dem betreffenden Online-Shop oder Anbieter eine Provision. F\u00fcr Dich ver\u00e4ndert sich der Preis nicht. Falls Du Deine Eink\u00e4ufe \u00fcber diese Links t\u00e4tigst unterst\u00fctzt Du Nerdiy.de dabei auch in Zukunft weitere n\u00fctzliche Projekte anbieten zu k\u00f6nnen. \ud83d\ude42\u00a0<\/em><\/p>\n<hr \/>\n<h2>Voraussetzungen<\/h2>\n<p><strong>Hilfreiche Artikel:<\/strong><br \/>\nWeitere hilfreiche Informationen zu den Grundlagen des L\u00f6tens k\u00f6nnt Ihr im folgenden Artikel finden:<br \/>\n<em><a href=\"https:\/\/www.nerdiy.de\/howto-elektronik-mein-freund-der-loetkolben\/\"><strong>Elektronik &#8211; Mein Freund der L\u00f6tkolben<\/strong><\/a><\/em><\/p>\n<p>Speziellere Informationen zum SMD- und THT-L\u00f6ten k\u00f6nnt Ihr in den folgenden Artikeln finden:<br \/>\n<em><strong><a href=\"https:\/\/www.nerdiy.de\/loeten-smd-bauteile-per-hand-loeten\/\">Elektronik &#8211; SMD Bauteile per Hand verl\u00f6ten<\/a><br \/>\n<\/strong><\/em><em><strong><a href=\"https:\/\/www.nerdiy.de\/loeten-einstieg-fuer-anfaenger\/\">Elektronik &#8211; THT Bauteile per Hand verl\u00f6ten<\/a><\/strong><\/em><\/p>\n<p><strong>Ben\u00f6tigtes Material:<\/strong><\/p>\n<p><strong>In der folgenden Liste findet Ihr alle Teile die Ihr zur Umsetzung dieses Artikels ben\u00f6tigt.<\/strong><\/p>\n\n<p><strong>Ben\u00f6tigtes Werkzeug:<\/strong><\/p>\n<p><strong>In der folgenden Liste findet Ihr alle Werkzeuge die Ihr zur Umsetzung dieses Artikels ben\u00f6tigt.<\/strong><\/p>\n\n<hr \/>\n<h2>Die Entl\u00f6tpumpe<\/h2>\n<p>Hier das erste verf\u00fcgbare Werkzeug im Entl\u00f6t- Kampf gegen verbundene L\u00f6tstellen. Die Entl\u00f6tpumpe ist n\u00e4mlich eine Vakuumpumpe mit der Ihr fl\u00fcssiges L\u00f6tzinn aus Bohrungen absaugen k\u00f6nnt.<\/p>\n<p>Dazu wird die Entl\u00f6tpumpe vor Ihrem Einsatz gespannt. An der richtigen Stelle kann diese Spannung dann gel\u00f6st werden. Eine dadurch freigelassene Feder zieht einen Kolben sehr schnell zur\u00fcck, welcher durch das entstandene Vakuum den fl\u00fcssigen L\u00f6tzinn in die Pumpe saugt.<\/p>\n<p>Das klingt so beschrieben recht abstrakt, deswegen hier eine kleine Anleitung zur Handhabung einer Entl\u00f6tpumpe.<\/p>\n<hr \/>\n<h2>Entl\u00f6tlitze<\/h2>\n<p>Das zweite n\u00fctzliche Werkzeug im Kampf gegen Lot-Reste ist die Entl\u00f6tlitze. Entl\u00f6tlitze besteht im Prinzip aus einem mit Flussmittel getr\u00e4nkten Kupferdrahtgeflecht. Zum Entl\u00f6ten wird die Entl\u00f6tlitze auf das zu entfernende Lot gelegt und mit dem hei\u00dfen L\u00f6tkolben solange dagegen gedr\u00fcckt bis das zu entfernende Lot fl\u00fcssig wird. Durch das im Kupferdrahtgeflecht und das darin enthaltene Flussmittel entsteht dann eine Kapilarwirkung (eine Art Saugeffekt) der das fl\u00fcssige L\u00f6tzinn in das Kupferdrahtgeflecht der Entl\u00f6tlitze aufsaugt.<\/p>\n<hr \/>\n<h2>Zange<\/h2>\n<p>Auf den ersten Blick vielleicht nicht direkt ersichtlich, aber auch Zangen sind hervorragende Helfer. Gerade um falsch angel\u00f6tete Stiftleisten zu entfernen eignen sie sich hervorragend. Dazu wird das Lot an dem L\u00f6tpunkt einer Stiftleiste hei\u00df gemacht und der jeweilige Stift der Stiftleiste mit der Zange entfernt. Dazu aber sp\u00e4ter mehr.<\/p>\n<hr \/>\n<h2>Entfernen von THT-Bauteilen und Stiftleisten<\/h2>\n<p>THT-Bauteile (THT=Through Hole Technology=&#8221;Durchsteckmontage&#8221;) kennzeichnen sich dadurch, dass die Kontakte der Bauteile in Form von &#8220;Beinchen&#8221; durch die Platine gesteckt und auf der Unterseite verl\u00f6tet werden. Dies hat zwei Vorteile: Die Bauteile sind sehr leicht zu verl\u00f6ten und &#8211; einmal angel\u00f6tet &#8211; mechanisch sehr stabil mit der Leiterplatte verbunden.<\/p>\n<p>Einer der Nachteile ist jedoch, dass das Ausl\u00f6ten &#8211; besonders bei Bauteilen mit mehreren Bauteilen &#8211; nicht immer ganz leicht ist. Es kann passieren, dass zumindest das Bauteil dabei besch\u00e4digt oder zerst\u00f6rt wird. Ihr ben\u00f6tigt dazu eine Entl\u00f6tpumpe, ggf. einen Elektronik-Seitenschneider und eine Spitz-Zange.<\/p>\n<p>Erhitzt zun\u00e4chst mit dem L\u00f6tkolben das erste L\u00f6tauge des verl\u00f6teten Bauteils.<\/p>\n<p>Versucht nun mit der Entl\u00f6tpumpe das fl\u00fcssig gewordene Lot abzusaugen indem Ihr die Pumpe m\u00f6glichst senkrecht \u00fcber das L\u00f6tauge st\u00fclpt und &#8220;abdr\u00fcckt&#8221;.<\/p>\n<p>Wenn Ihr Gl\u00fcck habt sieht das L\u00f6tauge danach so aus.(BEISPIEL MIT SAUBEREM L\u00d6TAUGE)<\/p>\n<p>Es kann aber auch vorkommen, dass sich das Lot nicht Vollst\u00e4ndig entfernen l\u00e4sst. Dies kann zum Beispiel bei sehr kleinen Lochdurchmessern passieren oder wenn an das betreffende L\u00f6tauge mit einer gro\u00dfen Kupferfl\u00e4che verbunden ist. Im letzten Fall erkaltet das Lot nach dem entfernen des L\u00f6tkolbens so schnell, dass es sich nicht vollst\u00e4ndig absaugen l\u00e4sst.<\/p>\n<hr \/>\n<h2>Entfernen von SMD-Bauteilen<\/h2>\n<p>Das Entfernen von einfachen SMD-Bauteilen mit zwei Kontakten (wie z.B. bei Widerst\u00e4nden und Kondensatoren) ist oft leicht zu erledigen. Oft sogar ohne das jeweilige Bauteil zu besch\u00e4digen. Bei mehrpoligen SMD-Bauteilen wie RGB-LED&#8217;s oder IC&#8217;s wird es dagegen schon schwieriger.<\/p>\n<h3>Entfernen mit dem L\u00f6tkolben<\/h3>\n<p><strong>Bauteile mit zwei Kontakten:<\/strong><\/p>\n<p>Erhitzt die zwei Kontakte abwechselnd jeweils f\u00fcnf Sekunden lang mit dem L\u00f6tkolben&#8230;<\/p>\n<p>&#8230;bis das Lot langsam fl\u00fcssig wird.<\/p>\n<p>Dies wiederholt Ihr dann solange bis&#8230;<\/p>\n<p>&#8230;sich das Bauteil von der Platine abheben l\u00e4sst.<\/p>\n<h3>Bauteile mit mehreren Kontakten<\/h3>\n<p><strong>&#8220;Beinchen f\u00fcr Beinchen hochbiege&#8221;-Methode:<\/strong><\/p>\n<p>Bei dieser Methode werden die Beinchen einzeln erhitzt und soweit von der Leiterplatte hoch gebogen, dass sie nicht mehr mit dieser verbunden sind.<\/p>\n<p><strong>&#8220;Beinchen f\u00fcr Beinchen abknips&#8221;-Methode:<\/strong><\/p>\n<p>Bei dieser Methode werden die Beinchen einzeln erhitzt und abgeknipst um sie von der Leiterplatte zu trennen.<\/p>\n<p><strong>&#8220;Lotbr\u00fccken&#8221;-Methode:<\/strong><\/p>\n<p>Bei dieser Methode wird im Prinzip ein gro\u00dfer Lotklecks \u00fcber die zu l\u00f6senden Kontakte gelegt. Dadurch k\u00f6nnen dann alle Kontakte gleichzeitig erhitzt und von der Leiterplatte gel\u00f6st werden.<\/p>\n<h3>Entfernen mit Hei\u00dfluft<\/h3>\n<p>Entl\u00f6ten mit Hei\u00dfluft ist immer dann ratsam, wenn die Kontakte des zu entfernenden Bauteils mit dem L\u00f6tkolben entweder sehr schwer zu erreichen sind oder sehr viele Kontakte gel\u00f6st werden m\u00fcssen. In Beiden Situationen ist es schwierig alle Beine gleichzeitig zu erhitzen. Das Entl\u00f6ten mit Hei\u00dfluft ist aber die L\u00f6sung f\u00fcr beide Probleme. Das Bauteil und die darunter liegende Leiterplatte werden dabei Gro\u00dffl\u00e4chig erhitzt bis sich das Lot an allen Kontaktstellen soweit erw\u00e4rmt hat, dass sich das Bauteil einfach von der Leiterplatte abheben l\u00e4sst.<\/p>\n<p>Dabei ist es ratsam die umliegenden Bauteile vor der Hitze der Hei\u00dfen Luft zu sch\u00fctzen. Dies funktioniert durch abkleben oder abdecken der Umgebenen Bauteile.<\/p>\n<p>Legt die Platine mit dem zu entfernendem Bauteil auf eine Hitzefeste Unterlage.<\/p>\n<p>Erhitzt das Bauteil nun mit Hei\u00dfluft und pr\u00fcft nach einer Weile ob&#8230;<\/p>\n<p>&#8230;sich das Bauteil verschieben oder Abheben l\u00e4sst.<\/p>\n<p>Erw\u00e4rmt das Bauteil und dessen Kontakte so lange weiter bis es sich abheben l\u00e4sst.<\/p>\n<hr \/>\n<h2>Reinigen von L\u00f6tpads mit Entl\u00f6tlitze<\/h2>\n<p>Habt Ihr die ungewollten Bauteile erst mal entfernt habt Ihr sehr wahrscheinliche eine stark verdreckte Leiterplatte vor euch liegen. Flussmittelreste lassen sich dabei noch sehr leicht mit etwas Isopropanol entfernen. Mehr dazu im Artikel <em><a href=\"https:\/\/www.nerdiy.de\/howto-elektronik-mein-freund-der-loetkolben\/\"><strong>Elektronik &#8211; Mein Freund der L\u00f6tkolben<\/strong><\/a><\/em>.<\/p>\n<p>Bei Lotresten wird das ganze aber schon wesentlich komplizierter, denn diese lassen sich nicht einfach abwischen oder abkratzen. Gerade letzteres solltet Ihr vermeiden, weil dadurch schnell L\u00f6tpads oder sogar komplette Leiterbahnen abgerissen werden k\u00f6nnen. Um das Lot trotzdem von der Leiterplatte zu bekommen gen\u00fcgt schon ein klein wenig L\u00f6tlitze.<\/p>\n<p>Dr\u00fcckt dazu die Entl\u00f6tlitze mit einem L\u00f6tkolben auf das verdreckte L\u00f6tpad.<\/p>\n<p>Das darunterliegende Lot wird mit der Zeit fl\u00fcssig&#8230;<\/p>\n<p>&#8230;und durch die entstehenden Kapilareffekte in die Entl\u00f6tlitze gesaugt.<\/p>\n<hr \/>\n<h2>Flussmittel-Reste entfernen<\/h2>\n<p>Zum entfernen von Flussmittelresten eignet sich Isopropanol sehr gut. Flussmittelreste entstehen gerade beim THT-L\u00f6te immer. Das Flussmittel &#8220;spritzt&#8221; dabei manchmal etwas und landet eigentlich immer auf der umgebenden Leiterplatte.<\/p>\n<p>Um auch in kleinen Ecken zwischen den Bauteilen Isopropanol auftragen zu k\u00f6nnen, eignet sich ein Wattest\u00e4bchen.<\/p>\n<hr \/>\n<h2>Viel Spa\u00df mit dem Projekt<\/h2>\r\n<p>Ich hoffe bei euch hat alles wie beschrieben funktioniert. Falls nicht oder ihr Fragen oder Anregungen habt lasst es mich in den Kommentaren bitte wissen. Ich trage dies dann ggf. in den Artikel nach.<br \/>Auch Ideen f\u00fcr neue Projekte sind immer gerne willkommen. \ud83d\ude42<\/p>\r\n<p><strong>P.S. Viele dieser Projekte - besonders die Hardwareprojekte - kosten viel Zeit und Geld. Nat\u00fcrlich mache ich das weil ich Spa\u00df daran habe, aber wenn Du es cool findest, dass ich die Infos dazu mit Euch teile, w\u00fcrde ich mich \u00fcber eine kleine Spende an die Kaffeekasse freuen. \ud83d\ude42<\/strong><\/p>\r\n<p><a href=\"https:\/\/ko-fi.com\/nerdiy\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" style=\"border: 0px; height: 36px;\" src=\"https:\/\/i0.wp.com\/cdn.ko-fi.com\/cdn\/kofi4.png?resize=143%2C36&#038;ssl=1\" alt=\"Buy Me a Coffee at ko-fi.com\" width=\"143\" height=\"36\" border=\"0\" \/><\/a>\u00a0 \u00a0 \u00a0 \u00a0<input name=\"cmd\" type=\"hidden\" value=\"_s-xclick\" \/> <input name=\"hosted_button_id\" type=\"hidden\" value=\"UAZE9RMHJY7VJ\" \/> <input title=\"PayPal - The safer, easier way to pay online!\" alt=\"Donate with PayPal button\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/de_DE\/DE\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.paypal.com\/de_DE\/i\/scr\/pixel.gif?resize=1%2C1&#038;ssl=1\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer den Artikel Elektronik &#8211; Mein Freund der L\u00f6tkolben bereits gelesen hat, hat vllt. gemerkt, dass man \u00fcber dieses Thema tats\u00e4chlich ziemlich viel schreiben kann. Und dabei geht es nur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[149,7,86,90],"tags":[],"class_list":["post-5545","post","type-post","status-publish","format-standard","hentry","category-abendprojekt2h","category-basics","category-elektronik","category-faehigkeiten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...<\/title>\n<meta name=\"description\" content=\"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nerdiy.de\/de_de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...\" \/>\n<meta property=\"og:description\" content=\"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nerdiy.de\/de_de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/\" \/>\n<meta property=\"og:site_name\" content=\"nerdiy.de - DIY, Elektronik, 3D Druck und mehr...\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nerdiy.de\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nerdiy.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-05T20:18:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T19:59:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-news-pcb-entwicklung-hubctrlr-minifloorlamp-und-nanopxlv1-3-20201204-115525-scaled.jpg?fit=1920%2C2560&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nerdiyde\" \/>\n<meta name=\"twitter:site\" content=\"@nerdiyde\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/\"},\"author\":{\"name\":\"Fab\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#\\\/schema\\\/person\\\/f1579a71868adb0be60a74246d3e0908\"},\"headline\":\"HowTo: Elektronik &#8211; L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen\",\"datePublished\":\"2019-05-05T20:18:16+00:00\",\"dateModified\":\"2024-04-11T19:59:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/\"},\"wordCount\":1218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#organization\"},\"articleSection\":[\"Abendprojekt(&lt;2h)\",\"Basics\",\"Elektronik\",\"F\u00e4higkeiten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/\",\"url\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/\",\"name\":\"HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#website\"},\"datePublished\":\"2019-05-05T20:18:16+00:00\",\"dateModified\":\"2024-04-11T19:59:05+00:00\",\"description\":\"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HowTo: Elektronik &#8211; L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#website\",\"url\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/\",\"name\":\"nerdiy.de - DIY, Elektronik, 3D Druck und mehr...\",\"description\":\"Bei nerdiy.de dreht sich alles um Elektronik, Heimwerken, 3D-Druck, Smart Home und viele andere technische Themen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#organization\",\"name\":\"Nerdiy.de\",\"url\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/nerdiy.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/www.nerdiy.de-v1.0final180x180-1.png?fit=180%2C180&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/nerdiy.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/www.nerdiy.de-v1.0final180x180-1.png?fit=180%2C180&ssl=1\",\"width\":180,\"height\":180,\"caption\":\"Nerdiy.de\"},\"image\":{\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nerdiy.de\",\"https:\\\/\\\/x.com\\\/nerdiyde\",\"https:\\\/\\\/www.instagram.com\\\/nerdiy.de\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/nerdiyde\\\/\",\"https:\\\/\\\/www.youtube.com\\\/nerdiy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nerdiy.de\\\/de_de\\\/#\\\/schema\\\/person\\\/f1579a71868adb0be60a74246d3e0908\",\"name\":\"Fab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g\",\"caption\":\"Fab\"},\"sameAs\":[\"https:\\\/\\\/nerdiy.de\",\"https:\\\/\\\/www.facebook.com\\\/nerdiy.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nerdiy.de\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nerdiy-de\\\/\",\"http:\\\/\\\/www.pinterest.com\\\/nerdiyde\\\/\",\"https:\\\/\\\/x.com\\\/nerdiyde\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Nerdiy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...","description":"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nerdiy.de\/de_de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/","og_locale":"de_DE","og_type":"article","og_title":"HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...","og_description":"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.","og_url":"https:\/\/nerdiy.de\/de_de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/","og_site_name":"nerdiy.de - DIY, Elektronik, 3D Druck und mehr...","article_publisher":"https:\/\/www.facebook.com\/nerdiy.de","article_author":"https:\/\/www.facebook.com\/nerdiy.de\/","article_published_time":"2019-05-05T20:18:16+00:00","article_modified_time":"2024-04-11T19:59:05+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-news-pcb-entwicklung-hubctrlr-minifloorlamp-und-nanopxlv1-3-20201204-115525-scaled.jpg?fit=1920%2C2560&ssl=1","type":"image\/jpeg"}],"author":"Fab","twitter_card":"summary_large_image","twitter_creator":"@nerdiyde","twitter_site":"@nerdiyde","twitter_misc":{"Verfasst von":"Fab","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/#article","isPartOf":{"@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/"},"author":{"name":"Fab","@id":"https:\/\/nerdiy.de\/de_de\/#\/schema\/person\/f1579a71868adb0be60a74246d3e0908"},"headline":"HowTo: Elektronik &#8211; L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen","datePublished":"2019-05-05T20:18:16+00:00","dateModified":"2024-04-11T19:59:05+00:00","mainEntityOfPage":{"@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/"},"wordCount":1218,"commentCount":0,"publisher":{"@id":"https:\/\/nerdiy.de\/de_de\/#organization"},"articleSection":["Abendprojekt(&lt;2h)","Basics","Elektronik","F\u00e4higkeiten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/","url":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/","name":"HowTo: Elektronik - L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen - nerdiy.de - DIY, Elektronik, 3D Druck und mehr...","isPartOf":{"@id":"https:\/\/nerdiy.de\/de_de\/#website"},"datePublished":"2019-05-05T20:18:16+00:00","dateModified":"2024-04-11T19:59:05+00:00","description":"Read a huge collection of detailed Tutorials on Nerdiy.de about all kind of Software, Hardware and general maker topics.","breadcrumb":{"@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nerdiy.de\/howto-elektronik-loetverbindungen-loesen-reinigen-und-bauteile-entfernen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nerdiy.de\/de_de\/"},{"@type":"ListItem","position":2,"name":"HowTo: Elektronik &#8211; L\u00f6tverbindungen l\u00f6sen, reinigen und Bauteile entfernen"}]},{"@type":"WebSite","@id":"https:\/\/nerdiy.de\/de_de\/#website","url":"https:\/\/nerdiy.de\/de_de\/","name":"nerdiy.de - DIY, Elektronik, 3D Druck und mehr...","description":"Bei nerdiy.de dreht sich alles um Elektronik, Heimwerken, 3D-Druck, Smart Home und viele andere technische Themen.","publisher":{"@id":"https:\/\/nerdiy.de\/de_de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nerdiy.de\/de_de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nerdiy.de\/de_de\/#organization","name":"Nerdiy.de","url":"https:\/\/nerdiy.de\/de_de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nerdiy.de\/de_de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/04\/www.nerdiy.de-v1.0final180x180-1.png?fit=180%2C180&ssl=1","contentUrl":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/04\/www.nerdiy.de-v1.0final180x180-1.png?fit=180%2C180&ssl=1","width":180,"height":180,"caption":"Nerdiy.de"},"image":{"@id":"https:\/\/nerdiy.de\/de_de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nerdiy.de","https:\/\/x.com\/nerdiyde","https:\/\/www.instagram.com\/nerdiy.de\/","https:\/\/www.pinterest.de\/nerdiyde\/","https:\/\/www.youtube.com\/nerdiy"]},{"@type":"Person","@id":"https:\/\/nerdiy.de\/de_de\/#\/schema\/person\/f1579a71868adb0be60a74246d3e0908","name":"Fab","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cd8a2c5a20873f04ac46048f749a6f5335f6d9d3af744d9bb04f4052c44fca2?s=96&d=mm&r=g","caption":"Fab"},"sameAs":["https:\/\/nerdiy.de","https:\/\/www.facebook.com\/nerdiy.de\/","https:\/\/www.instagram.com\/nerdiy.de","https:\/\/www.linkedin.com\/company\/nerdiy-de\/","http:\/\/www.pinterest.com\/nerdiyde\/","https:\/\/x.com\/nerdiyde","https:\/\/www.youtube.com\/c\/Nerdiy"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9GM3g-1rr","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5534,"url":"https:\/\/nerdiy.de\/de_de\/howto-elektronik-mein-freund-der-loetkolben\/","url_meta":{"origin":5545,"position":0},"title":"HowTo: Elektronik &#8211; Mein Freund der L\u00f6tkolben","author":"Fab","date":"5. Mai 2019","format":false,"excerpt":"Selbst als Teilzeit-Nerd kommt man auf Dauer nicht wirklich um den L\u00f6tkolben herum. Sp\u00e4testens, wenn die erste Probeschaltung auf dem Steckbrett gut funktioniert hat und man den n\u00e4chsten Schaltungs-Evolution\u00e4ren Schritt gehen will ist es Zeit den L\u00f6tkolben zu schwingen. Als Kind hatte ich lange f\u00fcrchterlich Respekt vor diesem Ding. Es\u2026","rel":"","context":"In &quot;Basics&quot;","block_context":{"text":"Basics","link":"https:\/\/nerdiy.de\/de_de\/category\/basics\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/05\/www.nerdiy.de-howto-elektronik-mein-freund-der-loetkolben-20190510-165246-2.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/05\/www.nerdiy.de-howto-elektronik-mein-freund-der-loetkolben-20190510-165246-2.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/05\/www.nerdiy.de-howto-elektronik-mein-freund-der-loetkolben-20190510-165246-2.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/05\/www.nerdiy.de-howto-elektronik-mein-freund-der-loetkolben-20190510-165246-2.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/05\/www.nerdiy.de-howto-elektronik-mein-freund-der-loetkolben-20190510-165246-2.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":676,"url":"https:\/\/nerdiy.de\/de_de\/loeten-smd-bauteile-per-hand-loeten\/","url_meta":{"origin":5545,"position":1},"title":"HowTo: Elektronik &#8211; SMD Bauteile per Hand verl\u00f6ten","author":"Fab","date":"7. M\u00e4rz 2019","format":false,"excerpt":"Nach dem verl\u00f6ten von THT-Bauteilen ist das Verl\u00f6ten von SMD-Bauteilen gewisserma\u00dfen die K\u00f6nigsdisziplin unter den L\u00f6therausforderungen. Dabei nimmt die Schwierigkeit mit abnehmender Gr\u00f6\u00dfe der Bauteile zu. SMD steht f\u00fcr \"Surface Mounted Devices\" und wird manchmal auch als \"SMT\" bezeichnet, was soviel wie \"Surface Mounted Technology\" bedeuted. Hinter beiden Begriffen verbirgt\u2026","rel":"","context":"In &quot;Basics&quot;","block_context":{"text":"Basics","link":"https:\/\/nerdiy.de\/de_de\/category\/basics\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/03\/www.nerdiy.de-howto-elektronik-smd-bauteile-per-hand-verloeten-20190509-191002.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/03\/www.nerdiy.de-howto-elektronik-smd-bauteile-per-hand-verloeten-20190509-191002.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/03\/www.nerdiy.de-howto-elektronik-smd-bauteile-per-hand-verloeten-20190509-191002.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/03\/www.nerdiy.de-howto-elektronik-smd-bauteile-per-hand-verloeten-20190509-191002.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/03\/www.nerdiy.de-howto-elektronik-smd-bauteile-per-hand-verloeten-20190509-191002.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15473,"url":"https:\/\/nerdiy.de\/de_de\/howto-pxlblck-pxlblck_cassettelamp-aufbauen\/","url_meta":{"origin":5545,"position":2},"title":"HowTo: pxlBlck &#8211; pxlBlck_CassetteLamp aufbauen","author":"Fab","date":"13. M\u00e4rz 2021","format":false,"excerpt":"Mittlerweile geh\u00f6ren MP3-Player, Smartphhones und USB-Sticks mit 128GB und mehr Speicher zum Alltag. Musik zu speichern und zu transportieren ist deshalb so einfach wie nie geworden. Vor ca. 30 Jahren sah das noch anders aus. Der \"USB-Stick der 80er\/90er\" war die Kassette. Nat\u00fcrlich habe auch ich noch eine Menge davon\u2026","rel":"","context":"In &quot;Elektronik&quot;","block_context":{"text":"Elektronik","link":"https:\/\/nerdiy.de\/de_de\/category\/elektronik\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2021\/03\/www.nerdiy.de-dehowto-pxlblck-pxlblck_cassettelamp-aufbauenenhowto-pxlblck-build-your-own-pxlblck_cassettelamp-dsc01621-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2021\/03\/www.nerdiy.de-dehowto-pxlblck-pxlblck_cassettelamp-aufbauenenhowto-pxlblck-build-your-own-pxlblck_cassettelamp-dsc01621-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2021\/03\/www.nerdiy.de-dehowto-pxlblck-pxlblck_cassettelamp-aufbauenenhowto-pxlblck-build-your-own-pxlblck_cassettelamp-dsc01621-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2021\/03\/www.nerdiy.de-dehowto-pxlblck-pxlblck_cassettelamp-aufbauenenhowto-pxlblck-build-your-own-pxlblck_cassettelamp-dsc01621-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2021\/03\/www.nerdiy.de-dehowto-pxlblck-pxlblck_cassettelamp-aufbauenenhowto-pxlblck-build-your-own-pxlblck_cassettelamp-dsc01621-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5389,"url":"https:\/\/nerdiy.de\/de_de\/elektronik-funktionen-eines-multimeters\/","url_meta":{"origin":5545,"position":3},"title":"HowTo: Elektronik &#8211; Die Funktionen eines Multimeters (zur Fehlersuche nutzen)","author":"Fab","date":"27. April 2019","format":false,"excerpt":"Voltmeter, Amperemeter, Ohmmeter bzw. als \"kompaktes Ger\u00e4t\"=Multimeter sind die ultimativen Lebens- oder mindestens Gute-Laune-Retter wenn die selbst gebaute Schaltung mal nicht funktioniert. Manchmal passiert es halt, dass obwohl man sich detailliert an einen Aufbauplan gehalten hat, die gebaute Schaltung trotzdem nicht funktioniert. Sp\u00e4testens dann sitzt man nach der anfangs motiviert\u2026","rel":"","context":"In &quot;Elektrik&quot;","block_context":{"text":"Elektrik","link":"https:\/\/nerdiy.de\/de_de\/category\/elektrik\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/04\/www.nerdiy.de-elektronik-die-funktionen-eines-multimeters-zur-fehlersuche-nutzen-20190514-145133.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/04\/www.nerdiy.de-elektronik-die-funktionen-eines-multimeters-zur-fehlersuche-nutzen-20190514-145133.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/04\/www.nerdiy.de-elektronik-die-funktionen-eines-multimeters-zur-fehlersuche-nutzen-20190514-145133.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2019\/04\/www.nerdiy.de-elektronik-die-funktionen-eines-multimeters-zur-fehlersuche-nutzen-20190514-145133.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18239,"url":"https:\/\/nerdiy.de\/de_de\/howto-pxlblck-pxldigit_clock-mit-dem-pxldigit-pcb-aufbauen\/","url_meta":{"origin":5545,"position":4},"title":"HowTo: pxlBlck &#8211; pxlDigit_clock mit dem pxlDigit PCB aufbauen","author":"Fab","date":"23. M\u00e4rz 2022","format":false,"excerpt":"Die Idee zum pxlDigit_PCB ist mir beim Aufbau des pxlDigit (Artikel hier: https:\/\/nerdiy.de\/howto-elektronik-sieben-segment-ziffer-pxldigit-aus-ws2812-leds-bauen\/) gekommen. Dort wird das pxlDigit aus einzelnen WS2812-LED-Segmenten aufgebaut. Dazu m\u00fcssen die LEDs zuerst in das 3D gedruckte Geh\u00e4use eingeklebt und dann im Geh\u00e4use miteinander verl\u00f6tet werden. Besonders dieser Schritt ist aufgrund des mangelnden Platzes gar nicht\u2026","rel":"","context":"In &quot;3D-Druck&quot;","block_context":{"text":"3D-Druck","link":"https:\/\/nerdiy.de\/de_de\/category\/3d-druck\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2022\/03\/www.nerdiy.de-enhowto-pxlblck-build-pxldigit_clock-with-the-pxldigit-pcb-dsc06447-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2022\/03\/www.nerdiy.de-enhowto-pxlblck-build-pxldigit_clock-with-the-pxldigit-pcb-dsc06447-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2022\/03\/www.nerdiy.de-enhowto-pxlblck-build-pxldigit_clock-with-the-pxldigit-pcb-dsc06447-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2022\/03\/www.nerdiy.de-enhowto-pxlblck-build-pxldigit_clock-with-the-pxldigit-pcb-dsc06447-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2022\/03\/www.nerdiy.de-enhowto-pxlblck-build-pxldigit_clock-with-the-pxldigit-pcb-dsc06447-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7643,"url":"https:\/\/nerdiy.de\/de_de\/howto-pxlblck-die-pxlblck_ringclock-aufbauen\/","url_meta":{"origin":5545,"position":5},"title":"HowTo: pxlBlck &#8211; Die pxlBlck_RingClock aufbauen","author":"Fab","date":"18. Dezember 2020","format":false,"excerpt":"Die pxlBlck_RingClock ist der pxlBlck_SlotClock sehr \u00e4hnlich. Sie ist auch mithilfe einer 1\u00d760 LED-Matrix aufgebaut und kann die Uhrzeit nach dem gleichen Schema wie die pxlBlck_SlotClock darstellen. Jedoch ist der LED-Streifen bei der pxlBlck_RingClock in einem Ring und nicht in einer Scheibe verbaut. Dies macht das Design der Uhr noch\u2026","rel":"","context":"In &quot;3D-Druck&quot;","block_context":{"text":"3D-Druck","link":"https:\/\/nerdiy.de\/de_de\/category\/3d-druck\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-howto-pxlblck-pxlblck_ringclock-aufbauen-dsc00809-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-howto-pxlblck-pxlblck_ringclock-aufbauen-dsc00809-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-howto-pxlblck-pxlblck_ringclock-aufbauen-dsc00809-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-howto-pxlblck-pxlblck_ringclock-aufbauen-dsc00809-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nerdiy.de\/wp-content\/uploads\/2020\/12\/www.nerdiy.de-howto-pxlblck-pxlblck_ringclock-aufbauen-dsc00809-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/posts\/5545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/comments?post=5545"}],"version-history":[{"count":1,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/posts\/5545\/revisions"}],"predecessor-version":[{"id":20952,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/posts\/5545\/revisions\/20952"}],"wp:attachment":[{"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/media?parent=5545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/categories?post=5545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdiy.de\/de_de\/wp-json\/wp\/v2\/tags?post=5545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}